{"id":1512,"date":"2022-12-12T15:25:01","date_gmt":"2022-12-12T14:25:01","guid":{"rendered":"https:\/\/www.haustechnik-inar.eu\/?page_id=1512"},"modified":"2023-10-16T09:29:31","modified_gmt":"2023-10-16T07:29:31","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"<div  class='avia-button-wrap av-97e6g-f6bfbc8a143d44b1d7281f56d9cec854-wrap avia-button-center  avia-builder-el-0  el_before_av_heading  avia-builder-el-first '><a href='https:\/\/www.haustechnik-inar.eu\/it\/'  class='avia-button av-97e6g-f6bfbc8a143d44b1d7281f56d9cec854 av-link-btn avia-icon_select-yes-left-icon avia-size-large avia-position-center avia-color-theme-color'   aria-label=\"Home\"><span class='avia_button_icon avia_button_icon_left avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue821' data-av_iconfont='entypo-fontello' ><\/span><span class='avia_iconbox_title' >Home<\/span><\/a><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lbkwombx-608a8aea10bbedea99f90a182e78ba1c\">\n#top .av-special-heading.av-lbkwombx-608a8aea10bbedea99f90a182e78ba1c{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-lbkwombx-608a8aea10bbedea99f90a182e78ba1c .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lbkwombx-608a8aea10bbedea99f90a182e78ba1c .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lbkwombx-608a8aea10bbedea99f90a182e78ba1c av-special-heading-h1  avia-builder-el-1  el_after_av_button  el_before_av_textblock '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Cookie Policy<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<section  class='av_textblock_section av-lbkwp6bu-9b4fc7715214ee0606c6db031dd54f04 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Titolare del trattamento \u00e8<\/p>\n<p>Haustechnik INAR\u00a0d. Leonhard Verdorfer<br \/>\n39012 MERANO (BZ) \/ via San Floriano, 7<br \/>\nTel. +39 345 80 44 753<br \/>\nCod. Fisc.:\u00a0VRD LHR 71E15 F132D<br \/>\nPart. IVA: 02674330218<br \/>\nEmail: <a href=\"mailto:info@haustechnik-inar.eu\">info[at]haustechnik-inar.eu<\/a><br \/>\nWeb: <a href=\"https:\/\/www.haustechnik-inar.eu\">www.haustechnik-inar.eu<\/a><\/p>\n<p>Nel corso della navigazione il sito web acquisisce delle informazioni necessarie per consentire una corretta e sicura esperienza di navigazione, si pensi ad esempio agli indirizzi IP, MAC address, nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito,\u00a0e ogni altra informazione tecnica implicita nell\u2019uso dei protocolli di comunicazione di Internet.<\/p>\n<p>Cookie<br \/>\nIl nostro sito web utilizza cookie per garantire un corretto utilizzo della pagina web e per migliorarne l\u2019esperienza di utilizzo. La presente Policy fornisce informazioni circa le tipologie di cookie utilizzate, le finalit\u00e0 e le relative modalit\u00e0 di utilizzo limitatamente alla presente sito web.<\/p>\n<p>Cosa sono i cookie?<br \/>\nIl Provvedimento dell\u2019Autorit\u00e0 Garante per la Protezione dei Dati Personali in materia di cookie d.d. 8 maggio 2014 definisce i cookie come \u201cstringhe di testo di piccole dimensioni che i siti visitati dall\u2019utente inviano al suo terminale (solitamente al browser), dove vengono memorizzati per essere poi ritrasmessi agli stessi siti alla successiva visita del medesimo utente. Nel corso della navigazione su un sito, l\u2019utente pu\u00f2 ricevere sul suo terminale anche cookie che vengono inviati da siti o da web server diversi (c.d. \u201cterze parti\u201d), sui quali possono risiedere alcuni elementi (quali, ad esempio, immagini, mappe, suoni, specifici link a pagine di altri domini) presenti sul sito che lo stesso sta visitando\u201d.<br \/>\nI cookie possono essere utilizzati per varie finalit\u00e0 come, ad esempio, per l\u2019esecuzione di autenticazioni informatiche, memorizzazione di informazioni riferite a configurazioni delle macchine che accedono al server, siti web preferiti etc. Di seguito verranno illustrate le diverse tipologie di cookie utilizzate dalla nostra pagina web.<\/p>\n<p>Tipologie di Cookie<br \/>\nIn base alla normativa vigente in Italia, per l\u2019utilizzo dei cookie non sempre \u00e8 richiesto un espresso consenso dell\u2019utente. In particolare, non richiedono tale consenso i cookie c.d. \u201ctecnici\u201d, cio\u00e8 quelli utilizzati al solo fine di effettuare la trasmissione di una comunicazione su una rete di comunicazione elettronica, o nella misura strettamente necessaria per erogare un servizio esplicitamente richiesto dall\u2019utente. Si tratta, in altre parole, di cookie indispensabili per il funzionamento del sito o necessari per eseguire attivit\u00e0 richieste dall\u2019utente.<\/p>\n<p>Cookie tecnici<br \/>\nI cookie tecnici sono quei cookie indispensabili per una corretta navigazione sulla pagina web, conservati unicamente per la durata della navigazione. Tra i cookie tecnici, che non richiedono un consenso espresso per il loro utilizzo, il Garante per la protezione dei dati personali (cfr. Prov. Gen. \u201cIndividuazione delle modalit\u00e0 semplificate per l\u2019informativa e l\u2019acquisizione del consenso per l\u2019uso dei cookie \u2013 8 maggio 2014 ) ricomprende anche:<\/p>\n<p>i \u201ccookie analytics\u201d laddove utilizzati direttamente dal gestore del sito per raccogliere informazioni, in forma aggregata, sul numero degli utenti e su come questi visitano il sito stesso,<br \/>\ni cookie di navigazione o di sessione (per autenticarsi, per realizzare un acquisto, ecc.),<br \/>\ni cookie di funzionalit\u00e0, che permettono all\u2019utente la navigazione in funzione di una serie di criteri selezionati (ad esempio, la lingua, i prodotti selezionati per l\u2019acquisto) al fine di migliorare il servizio reso allo stesso.<br \/>\nPer i cookie cc.dd. di profilazione, viceversa, cio\u00e8 quelli volti a creare profili relativi all\u2019utente e utilizzati al fine di inviare messaggi pubblicitari in linea con le preferenze manifestate dallo stesso nell\u2019ambito della navigazione in rete, \u00e8 richiesto un preventivo consenso dell\u2019utente.<\/p>\n<p>Cookie analitici<br \/>\nsono cookie utilizzati per monitorare il numero delle visite e l\u2019utilizzo della pagina web a livello statistico, sulla base di informazioni aggregate. Questi cookie consentono di comprendere come il sito viene utilizzato dagli utenti. \u00a0Con questi cookie non vengono raccolte informazioni sull\u2019identit\u00e0 dell\u2019utente, n\u00e9 alcun dato personale: tali cookie sono equiparabili ai cookie tecnici, in quanto viene mascherata la quarta componente dell\u2019indirizzo IP. Le informazioni sono trattate in forma aggregata ed anonima.<\/p>\n<p>Cookie terze parti che vengono creati da altri siti<br \/>\nQuesti ultimi sono proprietari di alcuni dei contenuti, ad esempio annunci o immagini, che vengono visualizzati sulla pagina web che visiti. Su questi cookie il Titolare del trattamento non \u00e8 in grado di esercitare uno specifico controllo. Per ottenere informazioni su detti cookie e sulle loro caratteristiche e modalit\u00e0 di funzionamento, rivolgersi direttamente a dette parti terze. L\u2019utilizzo di cookie di terze parti pu\u00f2 normalmente essere inibito dall\u2019utente anche attraverso l\u2019apposita opzione presente nel proprio programma di navigazione (browser).<\/p>\n<p>Il sito utilizza non utilizza cookie di profilazione.<\/p>\n<p>Il presente sito Internet utilizza solamente cookie tecnici e cookie analitici. Per tale ultima categoria, il Titolare del trattamento ha inoltre provveduto a rendere parzialmente anonimo l\u2019indirizzo IP dell\u2019utente, limitando cos\u00ec le informazioni a cui Matomo Analytics pu\u00f2 accedere. Banner al primo accesso. Il banner che appare sulla pagina web al primo accesso fornisce all\u2019utente indicazioni essenziali circa le modalit\u00e0 di gestione dei cookie del sito, rimandando alla cookie policy completa. L\u2019utente potr\u00e0 esprimere il proprio consenso all\u2019utilizzo dei cookie.<\/p>\n<p>Come disabilitare i Cookie?<br \/>\nRiportiamo di seguito i link ai principali Browser per modificare le scelte effettuate dall\u2019utente al primo accesso, in materia di cookie:<\/p>\n<ul>\n<li><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=de&amp;p=cpn_cookies\" target=\"_blank\" rel=\"noopener nofollow\">Google Chrome<\/a><\/li>\n<li><a href=\"https:\/\/support.mozilla.org\/de\/kb\/cookies-erlauben-und-ablehnen\" target=\"_blank\" rel=\"noopener nofollow\">Mozilla Firefox<\/a><\/li>\n<li><a href=\"https:\/\/support.apple.com\/de-de\/guide\/safari\/manage-cookies-and-website-data-sfri11471\" target=\"_blank\" rel=\"noopener nofollow\">Apple Safari<\/a><\/li>\n<li><a href=\"http:\/\/windows.microsoft.com\/de-de\/windows-vista\/block-or-allow-cookies\" target=\"_blank\" rel=\"noopener nofollow\">Microsoft Internet Explorer<\/a><\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/de-de\/help\/4027947\" target=\"_blank\" rel=\"noopener nofollow\">Microsoft Edge<\/a><\/li>\n<li><a href=\"https:\/\/support.brave.com\/hc\/articles\/360022806212-How-do-I-use-Shields-while-browsing\" target=\"_blank\" rel=\"noopener nofollow\">Brave<\/a><\/li>\n<li><a href=\"https:\/\/help.opera.com\/de\/latest\/web-preferences\/#cookies\" target=\"_blank\" rel=\"noopener nofollow\">Opera<\/a><\/li>\n<\/ul>\n<\/div><\/section>\n<section  class='av_textblock_section av-lbkwq8ut-2434a30624f79c46c4ec4659bd7ad2e6 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Cookie-Info:<\/p>\n<div  class='avia-cookie-privacy avia-cookie-privacy-cookie-info avia-cookie-privacy-cookie-info-container '><\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5021,"featured_media":884,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1512","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy - Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige<\/title>\n<meta name=\"description\" content=\"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy - Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige\" \/>\n<meta property=\"og:description\" content=\"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/haustechnikinar.desleonhardverdorfer\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-16T07:29:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-FB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/\",\"url\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/\",\"name\":\"Cookie Policy - Haustechnik INAR \\\/ Riparazioni di elettrodomestici \\\/ Merano (BZ) Alto Adige\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/haustechnik-inar_logo-FB.jpg\",\"datePublished\":\"2022-12-12T14:25:01+00:00\",\"dateModified\":\"2023-10-16T07:29:31+00:00\",\"description\":\"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/haustechnik-inar_logo-FB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/haustechnik-inar_logo-FB.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/cookie-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/\",\"name\":\"Haustechnik INAR \\\/ Riparazioni di elettrodomestici \\\/ Merano (BZ) Alto Adige\",\"description\":\"Riparazioni di elettrodomestici  - Mercatino usato - Pezzi di ricambio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#organization\",\"name\":\"Haustechnik INAR d. Leonhard Verdorfer\",\"url\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/haustechnik-inar_logo-home-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/haustechnik-inar_logo-home-mobile.png\",\"width\":1030,\"height\":687,\"caption\":\"Haustechnik INAR d. Leonhard Verdorfer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.haustechnik-inar.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/haustechnikinar.desleonhardverdorfer\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy - Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige","description":"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Cookie Policy - Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige","og_description":"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer","og_url":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/","og_site_name":"Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige","article_publisher":"https:\/\/www.facebook.com\/haustechnikinar.desleonhardverdorfer\/","article_modified_time":"2023-10-16T07:29:31+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-FB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/","url":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/","name":"Cookie Policy - Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige","isPartOf":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/#primaryimage"},"image":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-FB.jpg","datePublished":"2022-12-12T14:25:01+00:00","dateModified":"2023-10-16T07:29:31+00:00","description":"Cookie Policy - Haustechnik INAR d. Leonhard Verdorfer","breadcrumb":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/#primaryimage","url":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-FB.jpg","contentUrl":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-FB.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.haustechnik-inar.eu\/it\/cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.haustechnik-inar.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.haustechnik-inar.eu\/it\/#website","url":"https:\/\/www.haustechnik-inar.eu\/it\/","name":"Haustechnik INAR \/ Riparazioni di elettrodomestici \/ Merano (BZ) Alto Adige","description":"Riparazioni di elettrodomestici  - Mercatino usato - Pezzi di ricambio","publisher":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haustechnik-inar.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.haustechnik-inar.eu\/it\/#organization","name":"Haustechnik INAR d. Leonhard Verdorfer","url":"https:\/\/www.haustechnik-inar.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.haustechnik-inar.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-home-mobile.png","contentUrl":"https:\/\/www.haustechnik-inar.eu\/wp-content\/uploads\/2016\/08\/haustechnik-inar_logo-home-mobile.png","width":1030,"height":687,"caption":"Haustechnik INAR d. Leonhard Verdorfer"},"image":{"@id":"https:\/\/www.haustechnik-inar.eu\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/haustechnikinar.desleonhardverdorfer\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/pages\/1512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/users\/5021"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":0,"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/pages\/1512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/media\/884"}],"wp:attachment":[{"href":"https:\/\/www.haustechnik-inar.eu\/it\/wp-json\/wp\/v2\/media?parent=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}